 {"id":4375,"date":"2026-08-05T20:21:39","date_gmt":"2026-08-05T20:21:39","guid":{"rendered":"https:\/\/evalcompany.com\/?post_type=faq&#038;p=4375"},"modified":"2026-08-05T20:21:39","modified_gmt":"2026-08-05T20:21:39","slug":"ou-devez-vous-envoyer-vos-releves-de-notes","status":"publish","type":"faq","link":"https:\/\/evalcompany.com\/fr\/centre-daide\/ou-devez-vous-envoyer-vos-releves-de-notes\/","title":{"rendered":"O\u00f9 devez-vous envoyer vos relev\u00e9s de notes officiels ?"},"content":{"rendered":"<p class=\"wp-block-paragraph\">T\u00e9l\u00e9chargez des copies num\u00e9ris\u00e9es claires ou des photographies de vos relev\u00e9s de notes officiels via le portail de candidature en ligne du TEC.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsque les relev\u00e9s de notes doivent \u00eatre soumis directement \u00e0 des fins de v\u00e9rification, ils doivent \u00eatre envoy\u00e9s par l'\u00e9tablissement \u00e9metteur \u2014 et non par le candidat \u2014 selon l'une des m\u00e9thodes suivantes :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Courriel :<\/strong> <a href=\"mailto:verification@evalcompany.com\">verification@evalcompany.com<\/a><br>Les documents doivent \u00eatre envoy\u00e9s depuis une adresse e-mail institutionnelle officielle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>E-mail<\/strong><br>The Evaluation Company<br>2400 Augusta Drive, Bureau 451<br>Houston, TX 77057<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les documents de v\u00e9rification envoy\u00e9s par la poste doivent \u00eatre adress\u00e9s au bureau de Houston. Les envoyer aux bureaux de TEC \u00e0 New York ou Miami pourrait retarder votre \u00e9valuation.<\/p>\n\n\n\n<div style=\"box-sizing:border-box;width:calc(100vw - 12vw);margin:34px 0 0;margin-left:calc(50% - 50vw + 6vw);padding:22px 44px;background:#f1f2f7;border-radius:12px;display:flex;align-items:center;justify-content:space-between;gap:14px;flex-wrap:wrap;font-family:'Manrope',sans-serif;\">\n  <span style=\"font-size:16px;color:#3c4254;\">Besoin d'aide suppl\u00e9mentaire ?<\/span>\n  <a href=\"https:\/\/evalcompany.com\/fr\/formulaire-de-contact\/\" style=\"background:#232a6b;color:#fff;border-radius:20px;padding:10px 18px;font-size:14px;font-weight:700;text-decoration:none;\">Contactez-nous<\/a>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Upload clear scanned copies or photographs of your official transcripts through TEC\u2019s online application portal. When transcripts must be submitted directly for verification, they should be sent by the issuing institution\u2014not by the applicant\u2014using one of the following methods: Email: verification@evalcompany.comThe documents must be sent from an official institutional email address. Mail:The Evaluation Company2400 Augusta [&hellip;]<\/p>\n","protected":false},"template":"","class_list":["post-4375","faq","type-faq","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/evalcompany.com\/fr\/wp-json\/wp\/v2\/faq\/4375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evalcompany.com\/fr\/wp-json\/wp\/v2\/faq"}],"about":[{"href":"https:\/\/evalcompany.com\/fr\/wp-json\/wp\/v2\/types\/faq"}],"wp:attachment":[{"href":"https:\/\/evalcompany.com\/fr\/wp-json\/wp\/v2\/media?parent=4375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}