 {"id":4371,"date":"2026-08-05T20:21:39","date_gmt":"2026-08-05T20:21:39","guid":{"rendered":"https:\/\/evalcompany.com\/?post_type=faq&#038;p=4371"},"modified":"2026-08-05T20:21:39","modified_gmt":"2026-08-05T20:21:39","slug":"quand-la-verification-est-elle-requise","status":"publish","type":"faq","link":"https:\/\/evalcompany.com\/fr\/centre-daide\/quand-la-verification-est-elle-requise\/","title":{"rendered":"Quand la v\u00e9rification est-elle requise ?"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Pour les dipl\u00f4mes postsecondaires : la TEC exige l'authentification du dipl\u00f4me universitaire postsecondaire le plus \u00e9lev\u00e9 par pays d'\u00e9tudes ainsi que des titres professionnels de la plupart des pays.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour les dipl\u00f4mes secondaires : TEC exige l'authentification de la plupart des dipl\u00f4mes d'\u00e9tudes secondaires de la R\u00e9publique dominicaine, d'Ha\u00efti, du Vietnam et des pays membres du West African Examinations Council.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Veuillez noter que le destinataire de votre \u00e9valuation, s'il est sp\u00e9cifi\u00e9, peut avoir des exigences de v\u00e9rification allant au-del\u00e0 de la politique de la TEC \u00e9nonc\u00e9e ci-dessus \u2013 veuillez contacter votre \u00e9tablissement ou votre employeur pour plus de pr\u00e9cisions.<\/p>\n\n\n\n<div style=\"box-sizing:border-box;width:calc(100vw - 12vw);margin:34px 0 0;margin-left:calc(50% - 50vw + 6vw);padding:22px 44px;background:#f1f2f7;border-radius:12px;display:flex;align-items:center;justify-content:space-between;gap:14px;flex-wrap:wrap;font-family:'Manrope',sans-serif;\">\n  <span style=\"font-size:16px;color:#3c4254;\">Besoin d'aide suppl\u00e9mentaire ?<\/span>\n  <a href=\"https:\/\/evalcompany.com\/fr\/formulaire-de-contact\/\" style=\"background:#232a6b;color:#fff;border-radius:20px;padding:10px 18px;font-size:14px;font-weight:700;text-decoration:none;\">Contactez-nous<\/a>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>For post-secondary credentials: TEC requires authentication of the highest post-secondary academic credential per country of study as well as professional credentials from most countries. For secondary credentials: TEC requires authentication of most secondary school credentials from Vietnam, Dominican Republic, Haiti, and member countries of the West African Examinations Council. Please note that the recipient of [&hellip;]<\/p>\n","protected":false},"template":"","class_list":["post-4371","faq","type-faq","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/evalcompany.com\/fr\/wp-json\/wp\/v2\/faq\/4371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evalcompany.com\/fr\/wp-json\/wp\/v2\/faq"}],"about":[{"href":"https:\/\/evalcompany.com\/fr\/wp-json\/wp\/v2\/types\/faq"}],"wp:attachment":[{"href":"https:\/\/evalcompany.com\/fr\/wp-json\/wp\/v2\/media?parent=4371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}